{"id":1053,"date":"2026-03-09T16:36:26","date_gmt":"2026-03-09T15:36:26","guid":{"rendered":"https:\/\/new.icf.church\/zuerich\/?page_id=1053"},"modified":"2026-03-09T16:43:37","modified_gmt":"2026-03-09T15:43:37","slug":"ehrenkodex","status":"publish","type":"page","link":"https:\/\/icf.church\/zuerich\/de\/about\/ehrenkodex\/","title":{"rendered":"Ehrenkodex \u2013 ICF Z\u00fcrich Staff"},"content":{"rendered":"<div id=\"block-7\" class=\"pt-2 pb-2 alignfull is-layout-constrained\">\n  <div>\n            <div class=\"row gx-4 gy-4 \">\n          \n\n\n<div id=\"block-6\" class=\"col wp-block-yellowtree-column col-12 d-flex flex-column with-streched-height-children align-items-stretch align-items-md-stretch\">\n  <h1 id=\"block-1\" class=\"h1 display-1 text-start\">\n  Ehrenkodex<\/h1>\n\n<h3 id=\"block-2\" class=\"h3 text-start\">\n  f\u00fcr ICF Z\u00fcrich Staff<\/h3>\n\n<p id=\"block-3\" class=\"text-start wp-block-paragraph\">\n  <em>\u201eDeshalb wollen auch wir \u2013 wie L\u00e4ufer bei einem Wettkampf \u2013 mit aller Ausdauer dem Ziel entgegenlaufen. Wir wollen alles ablegen, was uns beim Laufen hindert, uns von der S\u00fcnde trennen, die uns so leicht gefangen nimmt, und unseren Blick auf Jesus richten, den Wegbereiter des Glaubens, der uns ans Ziel vorausgegangen ist.\u201c<\/em><\/p>\n\n<p id=\"block-4\" class=\"text-start wp-block-paragraph\">\n  <em>Die Bibel &#8211; Hebr\u00e4er 12,1-2 (NG\u00dc)<\/em><\/p>\n\n<p id=\"block-5\" class=\"text-start wp-block-paragraph\">\n  Als Angestellte und Core Leaders im ICF Z\u00fcrich ist es unser tiefer Wunsch, den Lauf des Glaubens siegreich zu vollenden. Wir sind entschlossen, nach biblisch-moralischen Standards zu leben. Nach zahlreichen Gespr\u00e4chen \u00fcber den Lebensstil als Leitende in der Kirche und inspiriert durch das \u201eModesto Manifesto\u201c von Billy Graham und seinen Freunden einigen wir uns auf eine Reihe von freiwilligen Grunds\u00e4tzen: Den \u201eEhrenkodex f\u00fcr ICF Z\u00fcrich Staff\u201c.<\/p><\/div>\n        <\/div>\n          <\/div>\n<\/div>\n\n<div id=\"block-18\" class=\"pt-2 pb-2 alignfull is-layout-constrained\">\n  <div>\n            <div class=\"row gx-4 gy-4 \">\n          \n\n\n<div id=\"block-17\" class=\"col wp-block-yellowtree-column col-12 d-flex flex-column with-streched-height-children align-items-stretch align-items-md-stretch\">\n  <div id=\"block-16\" class=\"accordion\">\n  <body>\n\n\n<div id=\"block-9\" data-bs-theme=\"dark\" class=\"overflow-hidden wp-block-yellowtree-accordion-item\">\n  <div class=\"accordion-header\">\n    <button class=\"accordion-button rounded-0 collapsed focus-ring-inset\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#block-9-collapse\" aria-expanded=\"false\" aria-controls=\"block-9-collapse\">\n      <div>\n        <h3 class=\"mb-0\">\n          L\u00f6hne und Finanzen        <\/h3>\n              <\/div>\n      <div class=\"ms-auto accordion-icons icon-container-base\">\n        <i class=\"icon fa-arrow-right accordion-icon-default\"><\/i>\n        <i class=\"icon fa-close accordion-icon-alt\"><\/i>\n      <\/div>\n    <\/button>\n  <\/div>\n  <div id=\"block-9-collapse\" class=\"accordion-collapse collapse \" data-bs-parent=\"#block-16\">\n    <div class=\"accordion-body pt-0\">\n      <p id=\"block-8\" class=\"text-start wp-block-paragraph\">\n  Die Kirche ICF Z\u00fcrich ist ein Verein. Dieser wird durch freiwillige Spenden finanziert. F\u00fcr alle Mitarbeitenden gilt ein von Provisionen unabh\u00e4ngiges Lohnmodell. Die Ertr\u00e4ge aus Verk\u00e4ufen aller ICF Media Produkte wie zum Beispiel B\u00fccher, Musik und Apps fliessen vollumf\u00e4nglich in die Organisation. Auf Anfrage gew\u00e4hren wir Einblick in unsere Finanzen. Mit \u00dcberzeugung erf\u00fcllen wir die gesetzlichen Bestimmungen, wie zum Beispiel die regelm\u00e4ssige Revision der Buchhaltung unserer Vereine.<\/p>    <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"block-11\" data-bs-theme=\"dark\" class=\"overflow-hidden wp-block-yellowtree-accordion-item\">\n  <div class=\"accordion-header\">\n    <button class=\"accordion-button rounded-0 collapsed focus-ring-inset\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#block-11-collapse\" aria-expanded=\"false\" aria-controls=\"block-11-collapse\">\n      <div>\n        <h3 class=\"mb-0\">\n          Gesundheit und Sexualit\u00e4t        <\/h3>\n              <\/div>\n      <div class=\"ms-auto accordion-icons icon-container-base\">\n        <i class=\"icon fa-arrow-right accordion-icon-default\"><\/i>\n        <i class=\"icon fa-close accordion-icon-alt\"><\/i>\n      <\/div>\n    <\/button>\n  <\/div>\n  <div id=\"block-11-collapse\" class=\"accordion-collapse collapse \" data-bs-parent=\"#block-16\">\n    <div class=\"accordion-body pt-0\">\n      <p id=\"block-10\" class=\"text-start wp-block-paragraph\">\n  Wir pflegen einen gesunden und suchtfreien Lebensstil. Sexueller S\u00fcnde wirken wir aktiv und in Selbstverantwortung entgegen. Gegen sexuellen Missbrauch und sexuelle Grenzverletzungen treffen wir als Organisation pr\u00e4ventive Massnahmen wie sensibilisiertes Bewerbungsverfahren, Personalschulungen und Verhaltenskodex f\u00fcr Mitarbeitende. Daf\u00fcr arbeiten wir mit der Fachstelle <a href=\"https:\/\/www.limita.ch\">\u201cLimita\u201d<\/a> zusammen. Jede Person unserer Kirche hat das Recht und die Pflicht, sich im Verdachtsfall an die nationale und unabh\u00e4ngige Fachstelle <a href=\"https:\/\/www.opferhilfe-schweiz.ch\">\u201cOpferhilfe\u201d<\/a> zu wenden.<\/p>    <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"block-13\" data-bs-theme=\"dark\" class=\"overflow-hidden wp-block-yellowtree-accordion-item\">\n  <div class=\"accordion-header\">\n    <button class=\"accordion-button rounded-0 collapsed focus-ring-inset\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#block-13-collapse\" aria-expanded=\"false\" aria-controls=\"block-13-collapse\">\n      <div>\n        <h3 class=\"mb-0\">\n          Macht und Kompetenzen        <\/h3>\n              <\/div>\n      <div class=\"ms-auto accordion-icons icon-container-base\">\n        <i class=\"icon fa-arrow-right accordion-icon-default\"><\/i>\n        <i class=\"icon fa-close accordion-icon-alt\"><\/i>\n      <\/div>\n    <\/button>\n  <\/div>\n  <div id=\"block-13-collapse\" class=\"accordion-collapse collapse \" data-bs-parent=\"#block-16\">\n    <div class=\"accordion-body pt-0\">\n      <p id=\"block-12\" class=\"text-start wp-block-paragraph\">\n  Wir unterstellen und verpflichten uns dem Leitbild von ICF Z\u00fcrich. Anvertraute Macht und Kompetenzen setzen wir verantwortungsbewusst ein und wirken Machtmissbrauch aktiv entgegen. Leo und Susanna Bigger leiten als Senior Pastors die Organisation und somit auch das Core Team als deren Leitungsteam. Im Core Team z\u00e4hlt jede Meinung. Wir ringen um Entscheidungen, bis alle sie mittragen k\u00f6nnen und niemand mehr schwerwiegende Vorbehalte hat. Die strategische und operative Verantwortung ist den jeweiligen Bereichen, Nebenbetrieben und Locations im Sinne von selbstorganisierten Teams zugeteilt. Die Kompetenzen in den juristischen Zweigen der Organisation sind jeweils auf zwei Unterschriftsberechtigte verteilt.<\/p>    <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"block-15\" data-bs-theme=\"dark\" class=\"overflow-hidden wp-block-yellowtree-accordion-item\">\n  <div class=\"accordion-header\">\n    <button class=\"accordion-button rounded-0 collapsed focus-ring-inset\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#block-15-collapse\" aria-expanded=\"false\" aria-controls=\"block-15-collapse\">\n      <div>\n        <h3 class=\"mb-0\">\n          Glaubw\u00fcrdigkeit und Integrit\u00e4t        <\/h3>\n              <\/div>\n      <div class=\"ms-auto accordion-icons icon-container-base\">\n        <i class=\"icon fa-arrow-right accordion-icon-default\"><\/i>\n        <i class=\"icon fa-close accordion-icon-alt\"><\/i>\n      <\/div>\n    <\/button>\n  <\/div>\n  <div id=\"block-15-collapse\" class=\"accordion-collapse collapse \" data-bs-parent=\"#block-16\">\n    <div class=\"accordion-body pt-0\">\n      <p id=\"block-14\" class=\"text-start wp-block-paragraph\">\n  Unsere ver\u00f6ffentlichten Zahlen und Statistiken sind wahrheitsgetreu. Wir haben eine unabh\u00e4ngige, externe und weisungsfreie Clearing-Stelle (Ombudsstelle) beauftragt und eingesetzt. Jede Person aus der Kirche und ihrem Umfeld hat die M\u00f6glichkeit, sich bei Konflikten mit Leiterschaft, Verdacht auf Machtmissbrauch oder Beobachtung ungesunder Verhaltensweisen dort zu melden. Informationen und Links: <a href=\"https:\/\/www.icf.church\/clearing-stelle\">www.icf.church\/clearing-stelle<\/a>.<\/p>    <\/div>\n  <\/div>\n<\/div>\n<\/body><\/div><\/div>\n        <\/div>\n          <\/div>\n<\/div>\n\n<div id=\"block-21\" class=\"pt-2 pb-2 alignfull is-layout-constrained\">\n  <div>\n            <div class=\"row gx-4 gy-4 \">\n          \n\n\n<div id=\"block-20\" class=\"col wp-block-yellowtree-column col-12 d-flex flex-column with-streched-height-children align-items-stretch align-items-md-stretch\">\n  <p id=\"block-19\" class=\"text-start wp-block-paragraph\">\n  <strong>M\u00f6ge Gott uns helfen, treu, leidenschaftlich und vorbildlich zu leben.<\/strong><\/p><\/div>\n        <\/div>\n          <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":189,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[{"url":"","title":"","desc":"","thumbnail":"","duration":"","rating":"","view_count":"","tag":""}],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"yt_custom_styles_scss":"","yt_custom_styles_rounded_corners":false,"yt_custom_styles_color_scheme":"","footnotes":""},"class_list":["post-1053","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages\/1053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/comments?post=1053"}],"version-history":[{"count":4,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages\/1053\/revisions"}],"predecessor-version":[{"id":1067,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages\/1053\/revisions\/1067"}],"up":[{"embeddable":true,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages\/189"}],"wp:attachment":[{"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/media?parent=1053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}