{"id":526,"date":"2025-09-15T10:59:25","date_gmt":"2025-09-15T08:59:25","guid":{"rendered":"https:\/\/new.icf.church\/zuerich\/?page_id=526"},"modified":"2026-07-05T09:10:27","modified_gmt":"2026-07-05T07:10:27","slug":"updates","status":"publish","type":"page","link":"https:\/\/icf.church\/zuerich\/de\/updates\/","title":{"rendered":"News &amp; Updates"},"content":{"rendered":"<div id=\"block-5\" class=\"pb-2 alignfull is-layout-constrained\">\n  <div>\n            <div class=\"row gx-4 gy-4 \">\n          \n\n<div id=\"block-4\" class=\"col wp-block-yellowtree-column col-12 d-flex flex-column with-streched-height-children align-items-stretch align-items-md-stretch\">\n  <div class=\"has-context-height\">\n  <article id=\"block-3\" data-bs-theme=\"dark\" class=\"wp-block-yellowtree-container-card card has-context-height\">\n    <div class=\"card-body\">\n      <h3 id=\"block-1\" class=\"h3 display-3 text-start\">\n  News &amp; Updates direkt auf dein Smartphone<\/h3>\n\n<p id=\"block-2\" class=\"text-start wp-block-paragraph\">\n  Alle News, Angebote &amp; Events gibt&#8217;s direkt auf Telegram.<br>Und so abonnierst du unsere Channels:<\/p>    <\/div>\n  <\/article>\n<\/div><\/div>\n        <\/div>\n          <\/div>\n<\/div>\n\n<div id=\"block-18\" class=\"pt-2 pb-2 alignfull is-layout-constrained\">\n  <div>\n            <div class=\"row gx-4 gy-4 \">\n          \n\n<div id=\"block-9\" class=\"col wp-block-yellowtree-column col-12 col-lg-4 d-flex flex-column with-streched-height-children align-items-stretch align-items-lg-stretch\">\n  <article id=\"block-8\" data-bs-theme=\"dark\" class=\"wp-block-yellowtree-card card has-context-height\" style=\"--card-img-position:40% 41%\">\n        <img decoding=\"async\" width=\"716\" height=\"477\" src=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/join-telegram-716x477-1.jpg\" class=\"card-img-top\" alt=\"Smartphone display with Telegram app icon and text.\" draggable=\"false\" loading=\"lazy\" srcset=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/join-telegram-716x477-1.jpg 716w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/join-telegram-716x477-1-300x200.jpg 300w\" sizes=\"(max-width: 716px) 100vw, 716px\">    <div class=\"card-body\">\n    <h3 class=\"card-title\">Telegram App<\/h3>\n    <p class=\"card-text\">1. Lade die Telegram App auf dein Smartphone<\/p>\n    <div id=\"block-7\" class=\"wp-block-yellowtree-card-buttons card-buttons\">\n  \n\n  <div>\n    <a id=\"block-6\" href=\"https:\/\/telegram.org\/dl?tme\" target=\"_blank\" class=\"wp-block-yellowtree-card-button btn btn-sm btn-secondary\">\n      <span>Herunterladen<\/span>\n              <i class=\"icon fs-base-const fa-arrow-right\" aria-hidden=\"true\"><\/i>\n          <\/a>\n  <\/div>\n\n<\/div>  <\/div>\n<\/article><\/div>\n\n\n<div id=\"block-13\" class=\"col wp-block-yellowtree-column col-12 col-lg-4 d-flex flex-column with-streched-height-children align-items-stretch align-items-lg-stretch\">\n  <article id=\"block-12\" data-bs-theme=\"dark\" class=\"wp-block-yellowtree-card card has-context-height\" style=\"--card-img-position:50% 50%\">\n        <img decoding=\"async\" width=\"716\" height=\"477\" src=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/updates-telegram-716x477-1.jpg\" class=\"card-img-top\" alt=\"Junge Frau schaut auf ihr Smartphone im Freien bei Sonnenlicht.\" draggable=\"false\" loading=\"lazy\" srcset=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/updates-telegram-716x477-1.jpg 716w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/updates-telegram-716x477-1-300x200.jpg 300w\" sizes=\"(max-width: 716px) 100vw, 716px\">    <div class=\"card-body\">\n    <h3 class=\"card-title\">ICF Z\u00fcrich Channel<\/h3>\n    <p class=\"card-text\">2. Abonniere den ICF Z\u00fcrich Channel<\/p>\n    <div id=\"block-11\" class=\"wp-block-yellowtree-card-buttons card-buttons\">\n  \n\n  <div>\n    <a id=\"block-10\" href=\"https:\/\/www.icf.ch\/telegram\" target=\"_blank\" class=\"wp-block-yellowtree-card-button btn btn-sm btn-secondary\">\n      <span>Abonnieren<\/span>\n              <i class=\"icon fs-base-const fa-arrow-right\" aria-hidden=\"true\"><\/i>\n          <\/a>\n  <\/div>\n\n<\/div>  <\/div>\n<\/article><\/div>\n\n\n<div id=\"block-17\" class=\"col wp-block-yellowtree-column col-12 col-lg-4 d-flex flex-column with-streched-height-children align-items-stretch align-items-lg-stretch\">\n  <article id=\"block-16\" data-bs-theme=\"dark\" class=\"wp-block-yellowtree-card card has-context-height\" style=\"--card-img-position:50% 50%\">\n        <img decoding=\"async\" width=\"848\" height=\"477\" src=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/02-2-848x477-1.jpg\" class=\"card-img-top\" alt=\"Sechs junge Menschen sitzen im Park und unterhalten sich.\" draggable=\"false\" loading=\"lazy\" srcset=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/02-2-848x477-1.jpg 848w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/02-2-848x477-1-300x169.jpg 300w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/02-2-848x477-1-768x432.jpg 768w\" sizes=\"(max-width: 848px) 100vw, 848px\">    <div class=\"card-body\">\n    <h3 class=\"card-title\">Weitere Channels<\/h3>\n    <p class=\"card-text\">3. Finde weitere passende Channels z.B. f\u00fcr Altersgruppen oder Communities denen du beitreten kannst \u2013 diese sind direkt im ICF Z\u00fcrich Telegram Channel verlinkt.<\/p>\n    <div id=\"block-15\" class=\"wp-block-yellowtree-card-buttons card-buttons\">\n  \n\n  <div>\n    <a id=\"block-14\" href=\"https:\/\/t.me\/icfzurich\/226\" target=\"_blank\" class=\"wp-block-yellowtree-card-button btn btn-sm btn-secondary\">\n      <span>Entdecken<\/span>\n              <i class=\"icon fs-base-const fa-arrow-right\" aria-hidden=\"true\"><\/i>\n          <\/a>\n  <\/div>\n\n<\/div>  <\/div>\n<\/article><\/div>\n        <\/div>\n          <\/div>\n<\/div>\n\n<div id=\"block-30\" class=\"pt-2 pb-2 alignfull is-layout-constrained\">\n  <div>\n            <div class=\"row gx-4 gy-4 \">\n          \n\n<div id=\"block-29\" class=\"col wp-block-yellowtree-column col-12 d-flex flex-column with-streched-height-children align-items-stretch align-items-md-stretch\">\n  <div class=\"has-context-height\">\n  <article id=\"block-28\" data-bs-theme=\"dark\" class=\"wp-block-yellowtree-container-card card has-context-height\">\n    <div class=\"card-body\">\n      <div>\n  <div id=\"block-26\" class=\"mt-4 mb-4 wp-block-yellowtree-connect-social connect-social\">\n      \n\n<h2 id=\"block-19\" class=\"text-center display-2 mb-5\">\n    Social Media<\/h2>\n\n\n<p id=\"block-20\" class=\"text-center mb-6\">\n    Auf Social Media findest du Ermutigung, Stories &amp; Momente aus unserer Community.<\/p>\n\n\n<div id=\"block-25\" class=\"wp-block-yellowtree-connect-social-links d-flex gap-1 gap-md-5 justify-content-center\">\n  \n\n<a id=\"block-21\" href=\"https:\/\/t.me\/icfzurich\" target=\"_blank\" data-variation=\"telegram\" class=\"wp-block-yellowtree-connect-social-link btn\" aria-label=\"Telegram Link\">\n  <i class=\"icon connect-social-icon fs-md-lg-const fs-h3-const fa-brands fa-telegram\" aria-hidden=\"true\"><\/i>\n<\/a>\n\n\n<a id=\"block-22\" href=\"https:\/\/instagram.com\/icfzurich\/\" target=\"_blank\" data-variation=\"instagram\" class=\"wp-block-yellowtree-connect-social-link btn\" aria-label=\"Instagram Link\">\n  <i class=\"icon connect-social-icon fs-md-lg-const fs-h3-const fa-brands fa-instagram\" aria-hidden=\"true\"><\/i>\n<\/a>\n\n\n<a id=\"block-23\" href=\"https:\/\/facebook.com\/icfzurich\" target=\"_blank\" data-variation=\"facebook\" class=\"wp-block-yellowtree-connect-social-link btn\" aria-label=\"Facebook Link\">\n  <i class=\"icon connect-social-icon fs-md-lg-const fs-h3-const fa-brands fa-facebook\" aria-hidden=\"true\"><\/i>\n<\/a>\n\n\n<a id=\"block-24\" href=\"https:\/\/youtube.com\/@icfchurch.zurich\" target=\"_blank\" data-variation=\"youtube\" class=\"wp-block-yellowtree-connect-social-link btn\" aria-label=\"Youtube Link\">\n  <i class=\"icon connect-social-icon fs-md-lg-const fs-h3-const fa-brands fa-youtube\" aria-hidden=\"true\"><\/i>\n<\/a>\n<\/div>\n  <\/div>\n<\/div>\n\n\n<p id=\"block-27\" class=\"fs-sm text-center wp-block-paragraph\">\n  <em>@icfzurich<\/em> | <em>#icfzurich<\/em><\/p>    <\/div>\n  <\/article>\n<\/div><\/div>\n        <\/div>\n          <\/div>\n<\/div>\n\n<div id=\"block-38\" class=\"pt-2 pb-2 alignfull is-layout-constrained\">\n  <div>\n            <div class=\"row gx-4 gy-4 \">\n          \n\n<div id=\"block-37\" class=\"col wp-block-yellowtree-column col-12 d-flex flex-column with-streched-height-children align-items-stretch align-items-md-stretch\">\n  <div id=\"block-36\" class=\"wp-block-yellowtree-text-image d-flex flex-column flex-lg-row gap-3\">\n    \n\n<div id=\"block-31\" class=\"wp-block-yellowtree-locked-image\">\n    <img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/dk5_8387-1140x641-1-1024x576.jpeg\" class=\"w-100 h-100 object-fit-cover\" alt=\"Zwei Menschen sitzen auf einer Couch und sprechen mit Mikrofonen.\" style=\"object-position: 34% 49%;\" loading=\"lazy\" sizes=\"(max-width: 992px) 100vw, 1600px\" srcset=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/dk5_8387-1140x641-1-1024x576.jpeg 1024w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/dk5_8387-1140x641-1-300x169.jpeg 300w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/dk5_8387-1140x641-1-768x432.jpeg 768w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/07\/dk5_8387-1140x641-1.jpeg 1140w\"><\/div>\n\n\n\n<div id=\"block-35\" data-bs-theme=\"dark\" class=\"card wp-block-yellowtree-text-card has-context-height\">\n  <div class=\"card-body px-4 py-6 p-sm-6 p-lg-8\">\n    \n\n<h2 id=\"block-32\">\n    Church Box<\/h2>\n\n\n<p id=\"block-33\">\n    Das monatliches Video Format mit Geschichten und Einblicke hinter die Kulissen von ICF.<\/p>\n\n\n  <div>\n    <a id=\"block-34\" href=\"https:\/\/www.youtube.com\/playlist?list=PLXImG20e6sCgVzcZaxtIaviONNrJgmFpV\" rel=\"\" target=\"_blank\" class=\"wp-block-yellowtree-button-link btn btn-default\">\n      <span>Jetzt ansehen<\/span>\n          <\/a>\n  <\/div>\n\n  <\/div>\n<\/div>\n<\/div><\/div>\n        <\/div>\n          <\/div>\n<\/div>\n\n<div id=\"block-46\" class=\"pt-2 pb-2 alignfull is-layout-constrained\">\n  <div>\n            <div class=\"row gx-4 gy-4 \">\n          \n\n<div id=\"block-45\" class=\"col wp-block-yellowtree-column col-12 d-flex flex-column with-streched-height-children align-items-stretch align-items-md-stretch\">\n  <div id=\"block-44\" class=\"wp-block-yellowtree-text-image d-flex flex-column flex-lg-row gap-3\">\n    \n\n<div id=\"block-39\" class=\"wp-block-yellowtree-locked-image\">\n    <img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/06\/email-newsletter-1024x768.jpg\" class=\"w-100 h-100 object-fit-cover\" alt=\"E-Mail-App-Icon mit roter Benachrichtigungszahl 2.\" style=\"object-position: 34% 49%;\" loading=\"lazy\" sizes=\"(max-width: 992px) 100vw, 1600px\" srcset=\"https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/06\/email-newsletter-1024x768.jpg 1024w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/06\/email-newsletter-300x225.jpg 300w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/06\/email-newsletter-768x576.jpg 768w, https:\/\/icf.church\/zuerich\/wp-content\/uploads\/sites\/2\/2026\/06\/email-newsletter.jpg 1500w\"><\/div>\n\n\n\n<div id=\"block-43\" data-bs-theme=\"dark\" class=\"card wp-block-yellowtree-text-card has-context-height\">\n  <div class=\"card-body px-4 py-6 p-sm-6 p-lg-8\">\n    \n\n<h2 id=\"block-40\">\n    News per E-Mail<\/h2>\n\n\n<p id=\"block-41\">\n    Erhalte Updates direkt in dein Postfach \u2013 zu besonderen Angeboten und Events.<\/p>\n\n\n  <div>\n    <a id=\"block-42\" href=\"https:\/\/forms.icf.ch\/t\/rBpnxSPhmmus\" rel=\"\" target=\"_blank\" class=\"wp-block-yellowtree-button-link btn btn-default\">\n      <span>Abonnieren<\/span>\n          <\/a>\n  <\/div>\n\n  <\/div>\n<\/div>\n<\/div><\/div>\n        <\/div>\n          <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[{"url":"","title":"","desc":"","thumbnail":"","duration":"","rating":"","view_count":"","tag":""}],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"yt_custom_styles_scss":"","yt_custom_styles_rounded_corners":false,"yt_custom_styles_color_scheme":"","footnotes":""},"class_list":["post-526","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages\/526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/comments?post=526"}],"version-history":[{"count":59,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages\/526\/revisions"}],"predecessor-version":[{"id":4073,"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/pages\/526\/revisions\/4073"}],"wp:attachment":[{"href":"https:\/\/icf.church\/zuerich\/de\/wp-json\/wp\/v2\/media?parent=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}